{"id":5431,"date":"2021-05-08T22:00:00","date_gmt":"2021-04-20T13:17:08","guid":{"rendered":"http:\/\/www.unilim.fr\/culture\/?page_id=5431"},"modified":"2021-05-16T19:10:51","modified_gmt":"2021-05-16T17:10:51","slug":"culture-numerique","status":"publish","type":"page","link":"https:\/\/www.unilim.fr\/culture\/culture-numerique\/","title":{"rendered":"Festival Etudiant Virtuel !"},"content":{"rendered":"        <div class=\"container-fluid  \" style=\"\">\n                      <div class=\"container\">\n                <div class=\"row \" style=\"margin-top: 30px;margin-bottom: 30px\">        <div class=\"col-sm-5 \">\n                    <div class=\"ul-element-image \">\n            <a href=\"https:\/\/www.unilim.fr\/culture\/wp-content\/uploads\/sites\/17\/2021\/03\/270-1.jpg\" target=\"\"  rel=\"lightbox\">\n                <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.unilim.fr\/culture\/wp-content\/uploads\/sites\/17\/2021\/03\/270-1.jpg\"\/>\n            <\/a>\n        <\/div>\n                <\/div>\n                <div class=\"col-sm-7 \">\n            <div class=\"ul-element-videojs \">\t\t\r\n\t\t<!-- Begin Video.js Responsive Wrapper -->\r\n\t\t<div style='max-width:1600px'>\r\n\t\t\t<div class='video-wrapper' style='padding-bottom:56.25%;'>\r\n\t\t\t\t\r\n\t<!-- Begin Video.js -->\r\n\t<video id=\"example_video_id_909533885\" class=\"video-js vjs-default-skin embed-responsive embed-responsive-16by9\" width=\"1600\" height=\"900\" controls preload=\"none\" data-setup='{\"forceSSL\":\"true\",\"techOrder\":[\"youtube\"],\"src\":\"https:\/\/youtu.be\/xriLLZVphWo\"}'>\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t<\/video>\r\n\t<!-- End Video.js -->\r\n\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<!-- End Video.js Responsive Wrapper -->\r\n\t\t<\/div>        <\/div>\n        <\/div>\n            <\/div>\n                  <\/div>\n                <div class=\"container-fluid  \" style=\"\">\n                      <div class=\"container\">\n                <div class=\"row \" style=\"margin-top: 30px;margin-bottom: 30px\">        <div class=\"col-sm-12 \">\n            \n        \n        <div class=\"ul-element-header text-left  \">\n\n            <h2 class=\"ul-bold  bg-primary\" style=\"padding:10px;\">\n                                EDITO                            <\/h2>\n        <\/div>\n                <div class=\"ul-element-image \">\n            <a href=\"https:\/\/www.unilim.fr\/culture\/wp-content\/uploads\/sites\/17\/2021\/04\/edito-1.jpg\" target=\"\"  rel=\"lightbox\">\n                <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.unilim.fr\/culture\/wp-content\/uploads\/sites\/17\/2021\/04\/edito-1.jpg\"\/>\n            <\/a>\n        <\/div>\n        \n        \n        <div class=\"ul-element-header text-center  \">\n\n            <h2 class=\"ul-bold  bg-primary\" style=\"padding:10px;\">\n                                FESTIVAL ETUDIANT 7\u00e8me Edition - JACES Journ\u00e9es des Arts et de la Culture dans l'Enseignement Sup\u00e9rieur                            <\/h2>\n        <\/div>\n                <div class=\"row\">\n                    <div class=\"col-sm-6\">\n                    <div class=\"clearfix ul-element-text \">\n            \n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Festival Etudiant&nbsp; \u00ab Les r\u00e9v\u00e9lations \u00bb&nbsp; &nbsp;\u00e0 suivre en ligne du 10 au 21 mai 2021<br \/>Invit\u00e9e d\u2019honneur Julie Gayet<br \/>Teaser :&nbsp;youtu.be\/xriLLZVphWo<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Programmation :&nbsp;<a href=\"https:\/\/filesender.renater.fr\/?s=download&amp;token=aadad252-b30e-4ffe-bd60-e27f63cd02fb\" data-mce-href=\"https:\/\/filesender.renater.fr\/?s=download&amp;token=aadad252-b30e-4ffe-bd60-e27f63cd02fb\">https:\/\/filesender.renater.fr\/?s=download&amp;token=aadad252-b30e-4ffe-bd60-e27f63cd02fb<\/a><\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">L\u2019\u00e9dition 2021 in\u00e9dite du festival \u00e9tudiant sera donc plac\u00e9e sous le signe du num\u00e9rique. Nous avons tenu \u00e0 le maintenir pour soutenir les cr\u00e9ations artistiques et culturelles des \u00e9tudiants et des personnels de l\u2019universit\u00e9 r\u00e9alis\u00e9es en distanciel pendant le confinement mais aussi et surtout pour cr\u00e9er du lien en cette p\u00e9riode troubl\u00e9e par la crise sanitaire.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Les cr\u00e9ations que nous proposons seront \u00e0 d\u00e9couvrir au rythme de chacun.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Toute la programmation et les liens de connexion \u00e0 d\u00e9couvrir sur la carte interactive active \u00e0 partir du 10 mai&nbsp; :&nbsp;https:\/\/www.unilim.fr\/jaces2021\/<br \/>Ne manquez pas nos soir\u00e9es en live ou en replay et les jeux concours en ligne !<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">10 mai 21h&nbsp;:&nbsp;Soir\u00e9e \u00e9tudiante en livestream ! Mix \u00ab CALL US \u00bb B2B par Watermeloon &amp; DJ SoundWave<br \/>11 mai 18h&nbsp;:&nbsp;Jeux en ligne<br \/>12 mai 19h&nbsp;:&nbsp;Enqu\u00eate virtuelle, Devenez le h\u00e9ros de Divine diva<br \/>28&nbsp;mai 16h30 :&nbsp;Rencontre avec Julie Gayet\/Documentaire football f\u00e9minin\/Courts m\u00e9trages \u00e9tudiants<br \/>18 mai 17h&nbsp;:&nbsp;Le\u00e7on de Cuisine \u00e0 la Chapelle St Martin<br \/>19 mai 18h :&nbsp;D\u00e9couverte du dispositif \u00ab Dans tous les sens \u00bb<br \/>20 mai 14h30 :&nbsp;Table ronde \u00ab&nbsp;Place de la culture dans le mal \u00eatre \u00e9tudiant&nbsp;\u00bb IUT Limoges. D\u00e9gustation de \u00ab&nbsp;ma madeleine \u00e0 tartiner&nbsp;\u00bb\/Musique \u00e9tudiante<br \/>L\u2019Universit\u00e9 de Limoges organise dans le cadre des Journ\u00e9es des Arts et de la culture dans l\u2019Enseignement Sup\u00e9rieur (JACES), son 7\u00e8me&nbsp;Festival Etudiant du 10 au 21 Mai 2021. En p\u00e9riode de confinement, le festival \u00e9tudiant sera majoritairement \u00e0 suivre en ligne, en streaming et en pr\u00e9sentiel.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Julie Gayet sera l\u2019invit\u00e9e d\u2019honneur de ce festival \u00e9tudiant 2021. Le 17 mai 2021 elle se rendra sur les campus \u00e0 la rencontre des \u00e9tudiants avant la diffusion de son documentaire sur le football f\u00e9minin et avant de d\u00e9couvrir les courts m\u00e9trages \u00e9tudiants qu\u2019elle pourra appr\u00e9cier et discuter lors d\u2019un \u00e9change pr\u00e9vu avec les \u00e9tudiants \u00e0 l\u2019origine de ces cr\u00e9ations.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Les spectacles propos\u00e9s pendant le festival le sont par des artistes professionnels accueillis \u00e0 l\u2019universit\u00e9. Il s\u2019agit aussi de spectacles cr\u00e9\u00e9s et interpr\u00e9t\u00e9s par des \u00e9tudiants engag\u00e9s dans les actions culturelles, issus du service culturel, des ateliers de pratiques culturelles, des associations \u00e9tudiantes ou par la participation active des partenaires du service culturel.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">La plupart de ces manifestations sont \u00e0 d\u00e9couvrir par la communaut\u00e9 universitaire et le grand public.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">L\u2019\u00e9dition 2021 sera donc plac\u00e9e sous le signe du num\u00e9rique pour soutenir les cr\u00e9ations artistiques et culturelles r\u00e9alis\u00e9es en distanciel pendant le confinement mais aussi et surtout pour cr\u00e9er du lien en cette p\u00e9riode troubl\u00e9e par la crise sanitaire.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Cette ann\u00e9e, les conditions sanitaires actuelles nous am\u00e8nent donc \u00e0 repenser l\u2019organisation in\u00e9dite de cet \u00e9v\u00e9nement qui se tiendra principalement en ligne. Les cr\u00e9ations seront \u00e0 d\u00e9couvrir \u00e0 son rythme.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Des nouveaux partenariats se mettent en place et notamment avec le Festival Z\u00e9ro1 de la Rochelle exclusivement tourn\u00e9 vers les arts num\u00e9riques.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Le festival \u00e9tudiant offre \u00e9galement l\u2019occasion pour les \u00e9tudiants de s\u2019immerger et de d\u00e9couvrir le monde du spectacle vivant autrement, de vivre une aventure culturelle engag\u00e9e et de c\u00f4toyer une nouvelle forme d\u2019art tout en s\u2019ouvrant au monde de la culture.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">L\u2019affiche est une cr\u00e9ation des \u00e9tudiants de l\u2019universit\u00e9 de la Rochelle.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Le visuel&nbsp;: Cl\u00e9ment Mauduit Universit\u00e9 de la Rochelle<br \/>Vignettes dessins&nbsp;: Patrick Trouillas Enseignant Chercheur Universit\u00e9 de Limoges<br \/>Programme complet sur le site internet de l\u2019Universit\u00e9 www.unilim.fr<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">Le Service Culturel remercie toutes les personnes et tous les partenaires qui se sont impliqu\u00e9s dans cette \u00e9dition in\u00e9dite \u00e9labor\u00e9e pendant le confinement.<\/p>\n<p style=\"text-align: justify\" data-mce-style=\"text-align: justify;\">FacebookTwitterLinkedIn<\/p>\n<p>&nbsp;<\/p>\n        <\/div>\n                <\/div>\n                <div class=\"col-sm-6\">\n                    <div class=\"ul-element-image \">\n            <a href=\"https:\/\/www.unilim.fr\/culture\/wp-content\/uploads\/sites\/17\/2021\/05\/image-03-112.jpg\" target=\"\"  rel=\"lightbox\">\n                <img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.unilim.fr\/culture\/wp-content\/uploads\/sites\/17\/2021\/05\/image-03-112.jpg\"\/>\n            <\/a>\n        <\/div>\n                <div class=\"clearfix ul-element-text \">\n            \n<p>Cr\u00e9dit photo Igor Shabalin<\/p>\n<p><\/p>\n        <\/div>\n                <\/div>\n                <\/div>\n                <\/div>\n        <\/div>\n            <\/div>\n                  <\/div>\n        \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":51,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-le.php","meta":{"footnotes":""},"class_list":["post-5431","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.unilim.fr\/culture\/wp-json\/wp\/v2\/pages\/5431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unilim.fr\/culture\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.unilim.fr\/culture\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.unilim.fr\/culture\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unilim.fr\/culture\/wp-json\/wp\/v2\/comments?post=5431"}],"version-history":[{"count":0,"href":"https:\/\/www.unilim.fr\/culture\/wp-json\/wp\/v2\/pages\/5431\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.unilim.fr\/culture\/wp-json\/wp\/v2\/media?parent=5431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}